{"id":2336,"date":"2022-06-24T13:19:31","date_gmt":"2022-06-24T13:19:31","guid":{"rendered":"https:\/\/www.dentled.com\/product\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/"},"modified":"2025-03-12T08:36:54","modified_gmt":"2025-03-12T08:36:54","slug":"phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche","status":"publish","type":"product","link":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/","title":{"rendered":"PHL14 DUO &#8211; Apparecchi a LED per sale di trattamento odontoiatriche"},"content":{"rendered":"<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"Dentled PHL22 full-spectrum, linear, and bidirectional LED lamps for dental treatment rooms.\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/qcbPoGUeRVc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n\t<section class=\"section\" id=\"section_1133706538\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-equal\"  id=\"row-233307703\">\n\n\t<div id=\"col-218918022\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3865549660\" class=\"text\">\n\t\t\n<h3>Per lavorare meglio<\/h3>\n\t\t\n<style>\n#text-3865549660 {\n  font-size: 2.25rem;\n  line-height: 1.25;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Dentled full-spectrum daylight LED lights create ideal working conditions for the dental practice. High-quality light is an important basis for the successful treatment of patients in a dental practice. In and of itself, natural daylight is the ideal light source for spatial orientation and focused, concentrated work. However, the structural conditions in practice rooms only allow sufficient daylight to enter through the window surfaces to a limited extent and in our latitudes only during the day. The lack of brightness for patient treatment has to be supplemented by artificial lighting.<\/p>\n\n  <div class=\"banner has-hover\" id=\"banner-1462145491\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-Praxis-beleuchting-Walter-dental-praxis.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1462145491 {\n  padding-top: 99.99%;\n  background-color: rgba(255, 255, 255, 0);\n}\n@media (min-width:550px) {\n  #banner-1462145491 {\n    padding-top: 550px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1771171659\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-2096878200\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-treatmentroom-Lighting-in-Paris-by-Dentled-PHL14.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2096878200 {\n  padding-top: 99.99%;\n  background-color: rgba(255, 255, 255, 0);\n}\n@media (min-width:550px) {\n  #banner-2096878200 {\n    padding-top: 550px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"gap-103185985\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-103185985 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h2><strong>La giusta luminanza<\/strong><\/h2>\n<p>Il rapporto di 10:1:0,5 pu\u00f2 essere utilizzato per un&#8217;illuminazione ottimale in una postazione di lavoro odontoiatrica. Questo \u00e8 il rapporto tra l&#8217;illuminazione del cavo orale da parte di una lampada chirurgica (20.000 lux per la maggior parte delle lampade da dentista, le nuove luci chirurgiche a LED spesso raggiungono valori ancora pi\u00f9 elevati fino a 55.000 lux), la vicinanza diretta della bocca (2.000 lux) e l&#8217;illuminamento nel resto della sala di trattamento (800-1.000 lux). <\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p><strong>Reclami comuni<\/strong> a causa di un&#8217;illuminazione errata del campo di lavoro: bruciore agli occhi, affaticamento, problemi di concentrazione e incapacit\u00e0 di determinare correttamente il colore. Investire in una soluzione di illuminazione di qualit\u00e0 per il tuo posto di lavoro \u00e8 essenziale per te e il tuo team. <\/p>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1133706538 {\n  padding-top: 50px;\n  padding-bottom: 50px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_851291086\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-403419407\">\n\n\t<div id=\"col-1510373946\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h2>Testimonianze<\/h2>\n<p>Guarda cosa dicono le persone<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1213169749\">\n\n\t<div id=\"col-1001686982\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-695359296\" >\n    <div class=\"slider slider-nav-dots-square slider-nav-circle slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row row-large\"  id=\"row-1598285412\">\n\n\t<div id=\"col-704845137\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover circle x md-x lg-x y md-y lg-y\" id=\"image_602096557\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-800x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4-1536x1536.jpg 1536w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/4.jpg 1620w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_602096557 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-704845137 > .col-inner {\n  padding: 15px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-876427765\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-255699046\">\n\n\t<div id=\"col-294276559\" class=\"col small-12 large-12\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"font-size: 300%\">&#8220;<\/span><\/h2>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-294276559 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<p><strong>Boca Sana<\/strong> Cliniche odontoiatriche \u2013 ex casa colonica ed \u00e8 stata convertita in modo molto professionale in un bellissimo studio dentistico dove, proprio come a Bunnik, \u00e8 stata scelta la luce diurna a spettro completo Dentled. Insieme ai proprietari Thomas de Leth e Peter Van der Eerden. \u2013 <a href=\"https:\/\/www.dentallighthouse.eu\/reference-practices\/custom-luminaires,dentled,fitted-panels\/boca-sana-dental-clinic-installation-with-dentled-by-henry-schein\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 <\/a>   <\/p>\n\t<div id=\"gap-958314916\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-958314916 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h4 style=\"margin-bottom: 0px\">Thomas de Leth<\/h4>\n<p><span style=\"font-size: 80%\">Dentista, proprietario BocaSana Clinics<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-large\"  id=\"row-1350622110\">\n\n\t<div id=\"col-125227348\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover circle x md-x lg-x y md-y lg-y\" id=\"image_1915717446\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Dentled Panels DL60\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-1536x1536.jpg 1536w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1.jpg 1620w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1915717446 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-125227348 > .col-inner {\n  padding: 15px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1542223037\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-140219276\">\n\n\t<div id=\"col-826209617\" class=\"col small-12 large-12\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"font-size: 300%\">&#8220;<\/span><\/h2>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-826209617 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<p>Henry Schein install\u00f2 le pi\u00f9 moderne apparecchiature odontoiatriche nella nuova clinica. Una soluzione LED a luce diurna a spettro completo era la nostra soluzione. Electro Rulfe fornisce la soluzione a Henry schein bij utilizzando DENLTED DL60.  <\/p>\n\t<div id=\"gap-175187090\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-175187090 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h4 style=\"margin-bottom: 0px\">Elektro Rufle per Zahnartz Murg Germania<\/h4>\n<p><span style=\"font-size: 80%\">Installatore  <\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-large\"  id=\"row-682673617\">\n\n\t<div id=\"col-2044694418\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover circle x md-x lg-x y md-y lg-y\" id=\"image_104115258\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-800x800.png\" class=\"attachment-large size-large\" alt=\"DENTLED TREAMENTROOM LIGHTING DENTIST\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-800x800.png 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-247x247.png 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-100x100.png 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-512x512.png 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-400x400.png 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-280x280.png 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3-768x768.png 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/3.png 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_104115258 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2044694418 > .col-inner {\n  padding: 15px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-45546361\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1816759294\">\n\n\t<div id=\"col-630447028\" class=\"col small-12 large-12\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"font-size: 300%\">&#8220;<\/span><\/h2>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-630447028 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<p><em>&#8220;Grazie per i buoni consigli e l&#8217;implementazione. &#8221; \u00c8 stata una gioia lavorare nella luce giusta oggi&#8221;<\/em><\/p>\n\t<div id=\"gap-266701309\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-266701309 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h4 style=\"margin-bottom: 0px\"><em>&#8211;<\/em> Mascha Koster Amsterdam.<\/h4>\n<p><span style=\"font-size: 80%\">DENTISTA<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1213169749 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n}\n@media (min-width:550px) {\n  #row-1213169749 > .col > .col-inner {\n    padding: 50px 50px 30px 50px;\n  }\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_851291086 {\n  padding-top: 80px;\n  padding-bottom: 80px;\n  background-color: rgb(246, 246, 246);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_947342699\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"text-190637827\" class=\"text\">\n\t\t\n<h1><span style=\"font-size: 120%\"><strong>Come lavoriamo<\/strong><\/span><\/h1>\n\t\t\n<style>\n#text-190637827 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-solid\"  id=\"row-2039328\">\n\n\t<div id=\"col-358861909\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/3.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/3.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/3-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>1. Condividi il tuo piano<\/h3>\n<p><span style=\"font-size: 90%\">Condividi la tua planimetria e noi creeremo un piano di illuminazione che include il calcolo del dialux con l&#8217;illuminazione giusta per la tua clinica o per i tuoi clienti.  <\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-123916298\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-1-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>2. Campione e offerta<\/h3>\n<p><span style=\"font-size: 90%\">Sulla base dell&#8217;offerta, possiamo spedirti un campione per la revisione.  <\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-590965514\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-2.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-2.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-2-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>3. Progetto e consegna<\/h3>\n<p><span style=\"font-size: 90%\">In base all&#8217;offerta concordata e alla data di installazione, finalizziamo l&#8217;ordine e lo consegniamo per l&#8217;installazione al vostro installatore o ufficio. Offriamo l&#8217;installazione su richiesta. <\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-2039328 > .col > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-552837184\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-552837184 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>I dispositivi PH sono disponibili in due dimensioni: 1405 mm e 2245 mm di lunghezza (\u00e8 incluso un rapporto di calcolo dialux per le sale di trattamento) <\/p>\n<p><strong>PHM14 monocromatico<\/strong>: \u2013 1x L1405\/W51\/H81mm<\/p>\n<p><strong>PHM22 monocromatico<\/strong>: \u2013 1 xL2245\/W51\/H81mm<\/p>\n<p><strong>PHL14 duo<\/strong>: \u2013 2 x L1405\/W51\/H81mm<\/p>\n<p><strong>PHL22 duo<\/strong>: \u2013 2 x L2245\/W51\/H81mm<\/p>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_947342699 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<h3><strong>Dentled full-spectrum daylight LED lights create ideal working conditions for the dental practice<\/strong><\/h3>\n<p>High-quality light is an important basis for the successful treatment of patients in a dental practice. In and of itself, natural daylight is the ideal light source for spatial orientation and focused, concentrated work. However, the structural conditions in practice rooms only allow sufficient daylight to enter through the window surfaces to a limited extent and in our latitudes only during the day. The lack of brightness for patient treatment has to be supplemented by artificial lighting.<\/p>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h4>PRODUCT SPECIFICATIONS<\/h4>\n<ul>\n<li>5200K<\/li>\n<li>42-60W adjustable<\/li>\n<li>UGR&lt;19<\/li>\n<li>Powerfactor 0.97<\/li>\n<li>CRi97<\/li>\n<li>Flicker Free Drivers ( Dali 2 )<\/li>\n<li>Pre mounted power cord<\/li>\n<li>50.000 hours ( ref: L90B10*)<\/li>\n<li>Aluminium frame \/\/ high quality 1.5 cm<\/li>\n<li>Color: RAL9003<\/li>\n<li>DALI 2<\/li>\n<li>GST<\/li>\n<\/ul>\n<p><span style=\"font-size: 90%\"><strong>50.000 hours ( ref: L90B10*) <\/strong>LB value indicate the real lifetime at a certain hours. Like L90B10 at 50,000 hours means <b>the LED lamp keeping 90% lumen from initial lumen and only 10% light failed to reach 90% lumen<\/b>. You can get clearly L70B50 means only 50% lamp survive at 70% lumen remaining at 50,000 hours.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t<section class=\"section\" id=\"section_1634369108\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-solid\"  id=\"row-835189859\">\n\n\t<div id=\"col-1420258431\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-4.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-4.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-4-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Luce diurna a spettro completo<\/h3>\n<p><span style=\"font-size: 90%\">Ti senti pi\u00f9 a tuo agio alla luce del giorno a spettro completo e ha propriet\u00e0 che causano meno affaticamento degli occhi.<\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-843081758\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/2-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Alto RA 97+<\/h3>\n<p><span style=\"font-size: 90%\">Eseguito in un colore di luce diurna con un valore RA di 97+ per una determinazione ottimale del colore.<\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-713980873\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-1.png 128w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Dentled-ICONS-1-100x100.png 100w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>2000 LUX<\/h3>\n<p><span style=\"font-size: 90%\">Nessuna influenza negativa sull&#8217;indurimento del composito e\/o della colla grazie alla luce diurna a spettro completo a 2000 lux<\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-835189859 > .col > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1057299779\">\n\n\t<div id=\"col-818413368\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center\"><strong>Guarda i progetti recenti con PHL14 DUO<\/strong><\/h3>\n<hr>\n<h3 style=\"text-align: center\"> <\/h3>\n<div id=\"portfolio-363666076\" class=\"portfolio-element-wrapper has-filtering\">\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n    <div class=\"col\" data-terms=\"[&quot;cliniche odontoiatriche&quot;]\" >\n          <div class=\"col-inner\" >\n          <a href=\"https:\/\/www.dentled.com\/it\/featured_item\/installazione-di-illuminazione-a-spettro-completo-presso-zahnarztpraxis-kokonzept-a-neukirchen-vluyn\/\" class=\"plain \">\n          <div class=\"portfolio-box box has-hover\">\n            <div class=\"box-image\" >\n                <div class=\"image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/10\/Vollspektrum-Beleuchtung-bei-der-Zahnarztpraxis-Kokonzept-in-Neukirchen-Vluyn.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n            <\/div>\n            <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h6 class=\"uppercase portfolio-box-title\">Installazione di illuminazione a spettro completo presso Zahnarztpraxis Ko&#8217;konzept a Neukirchen-Vluyn<\/h6>\n                      <p class=\"uppercase portfolio-box-category is-xsmall op-6\">\n                        <span class=\"show-on-hover\">\n                         cliniche odontoiatriche                        <\/span>\n                      <\/p>\n                  <\/div>\n            <\/div>\n           <\/div>\n           <\/a>\n           <\/div>\n           <\/div><div class=\"col\" data-terms=\"[&quot;cliniche odontoiatriche&quot;]\" >\n          <div class=\"col-inner\" >\n          <a href=\"https:\/\/www.dentled.com\/it\/featured_item\/studio-dentistico-venken-phm-apparecchi-a-luce-diurna\/\" class=\"plain \">\n          <div class=\"portfolio-box box has-hover\">\n            <div class=\"box-image\" >\n                <div class=\"image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dental-Studio-Venken-Dentled-PHM-full-spectrum-daylight.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n            <\/div>\n            <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h6 class=\"uppercase portfolio-box-title\">Studio Dentistico Venken PHM Apparecchi a luce diurna<\/h6>\n                      <p class=\"uppercase portfolio-box-category is-xsmall op-6\">\n                        <span class=\"show-on-hover\">\n                         cliniche odontoiatriche                        <\/span>\n                      <\/p>\n                  <\/div>\n            <\/div>\n           <\/div>\n           <\/a>\n           <\/div>\n           <\/div><div class=\"col\" data-terms=\"[&quot;cliniche odontoiatriche&quot;]\" >\n          <div class=\"col-inner\" >\n          <a href=\"https:\/\/www.dentled.com\/it\/featured_item\/caso-di-studio-miglioramento-dellilluminazione-nelle-sale-di-trattamento-dentale-presso-schurwaldpraxis-a-reichenbach-an-der-fils\/\" class=\"plain \">\n          <div class=\"portfolio-box box has-hover\">\n            <div class=\"box-image\" >\n                <div class=\"image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/09\/Praxis-beleuchtung-Behandlungraum-Dentled-LED.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n            <\/div>\n            <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h6 class=\"uppercase portfolio-box-title\">Caso di studio: Miglioramento dell&#8217;illuminazione nelle sale di trattamento dentale presso Schurwaldpraxis a Reichenbach an der Fils<\/h6>\n                      <p class=\"uppercase portfolio-box-category is-xsmall op-6\">\n                        <span class=\"show-on-hover\">\n                         cliniche odontoiatriche                        <\/span>\n                      <\/p>\n                  <\/div>\n            <\/div>\n           <\/div>\n           <\/a>\n           <\/div>\n           <\/div><div class=\"col\" data-terms=\"[&quot;Laboratorio odontotecnico&quot;]\" >\n          <div class=\"col-inner\" >\n          <a href=\"https:\/\/www.dentled.com\/it\/featured_item\/illuminazione-di-precisione-per-la-salute-e-laccuratezza-nei-laboratori-odontotecnici\/\" class=\"plain \">\n          <div class=\"portfolio-box box has-hover\">\n            <div class=\"box-image\" >\n                <div class=\"image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/11\/Dentled-PHW-Lighting-for-Dental-technical-offices-and-labs-2.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                                <\/div>\n            <\/div>\n            <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h6 class=\"uppercase portfolio-box-title\">Illuminazione di precisione per la salute e l&#8217;accuratezza nei laboratori odontotecnici<\/h6>\n                      <p class=\"uppercase portfolio-box-category is-xsmall op-6\">\n                        <span class=\"show-on-hover\">\n                         Laboratorio odontotecnico                        <\/span>\n                      <\/p>\n                  <\/div>\n            <\/div>\n           <\/div>\n           <\/a>\n           <\/div>\n           <\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1057299779 > .col > .col-inner {\n  padding: 30px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1634369108 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Apparecchio PHM con LED a luce diurna a spettro completo Dentled per sale di trattamento<\/p>\n<ul>\n<li><span style=\"font-size: 90%\">distribuzione della luce ottimale ed efficiente dal punto di vista energetico grazie all&#8217;illuminazione diretta e indiretta (<\/span><span style=\"font-size: 12.96px\">50.000+ ore L90B10) <\/span> <\/li>\n<li><span style=\"font-size: 90%\">un alto valore di RA di 93,5 che consente una determinazione del colore senza imperfezioni e UGR &lt;19 evita sgradevoli riflessi<\/span><\/li>\n<li><span style=\"font-size: 90%\">Nessuna influenza negativa sull&#8217;indurimento del composito e\/o della colla grazie alla luce diurna a spettro completo a 2000 lux  <\/span><\/li>\n<li><span style=\"font-size: 90%\">Soddisfa il minimo specificato di 2000 lux di illuminamento sul posto di lavoro (poggiatesta della poltrona in posizione di trattamento)<\/span><\/li>\n<li><span style=\"font-size: 90%\">L&#8217;utilizzo di driver flicker-free, meno faticoso per gli occhi evitando lo sfarfallio a 50Hz della sorgente luminosa<\/span><\/li>\n<li><span style=\"font-size: 90%\">9500 Lumen per apparecchio, Su: 2850 Lumen \/ Gi\u00f9: 5700 Lumen \u2013 5500-5700 Kelvin<\/span><\/li>\n<li><span style=\"font-size: 90%\">misura standard mono: Lunghezza 1405mm \u2013 Larghezza: 51mm \u2013 Altezza: 81mm<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-393\" src=\"http:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/IP40.jpg\" alt=\"DALI 2 IP40 Specifiche delle sale per trattamenti odontoiatrici Dentled\" width=\"350\" height=\"60\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/IP40.jpg 350w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/04\/IP40-247x42.jpg 247w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":2344,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":{"0":"post-2336","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-apparecchi","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche\" \/>\n<meta property=\"og:description\" content=\"Apparecchio PHM con LED a luce diurna a spettro completo Dentled per sale di trattamento  distribuzione della luce ottimale ed efficiente dal punto di vista energetico grazie all&#039;illuminazione diretta e indiretta (50.000+ ore L90B10)   un alto valore di RA di 93,5 che consente una determinazione del colore senza imperfezioni e UGR &lt;19 evita sgradevoli riflessi  Nessuna influenza negativa sull&#039;indurimento del composito e\/o della colla grazie alla luce diurna a spettro completo a 2000 lux   Soddisfa il minimo specificato di 2000 lux di illuminamento sul posto di lavoro (poggiatesta della poltrona in posizione di trattamento)  L&#039;utilizzo di driver flicker-free, meno faticoso per gli occhi evitando lo sfarfallio a 50Hz della sorgente luminosa  9500 Lumen per apparecchio, Su: 2850 Lumen \/ Gi\u00f9: 5700 Lumen \u2013 5500-5700 Kelvin  misura standard mono: Lunghezza 1405mm \u2013 Larghezza: 51mm \u2013 Altezza: 81mm  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentled com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T08:36:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/\",\"url\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/\",\"name\":\"PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dentled.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg\",\"datePublished\":\"2022-06-24T13:19:31+00:00\",\"dateModified\":\"2025-03-12T08:36:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dentled.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dentled.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"save energy, full spectrum daylight, better work, CRI97\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotto\",\"item\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/prodotto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PHL14 DUO &#8211; Apparecchi a LED per sale di trattamento odontoiatriche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/\",\"name\":\"Dentled com\",\"description\":\"Lighting for dental care\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/","og_locale":"it_IT","og_type":"article","og_title":"PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche","og_description":"Apparecchio PHM con LED a luce diurna a spettro completo Dentled per sale di trattamento  distribuzione della luce ottimale ed efficiente dal punto di vista energetico grazie all'illuminazione diretta e indiretta (50.000+ ore L90B10)   un alto valore di RA di 93,5 che consente una determinazione del colore senza imperfezioni e UGR &lt;19 evita sgradevoli riflessi  Nessuna influenza negativa sull'indurimento del composito e\/o della colla grazie alla luce diurna a spettro completo a 2000 lux   Soddisfa il minimo specificato di 2000 lux di illuminamento sul posto di lavoro (poggiatesta della poltrona in posizione di trattamento)  L'utilizzo di driver flicker-free, meno faticoso per gli occhi evitando lo sfarfallio a 50Hz della sorgente luminosa  9500 Lumen per apparecchio, Su: 2850 Lumen \/ Gi\u00f9: 5700 Lumen \u2013 5500-5700 Kelvin  misura standard mono: Lunghezza 1405mm \u2013 Larghezza: 51mm \u2013 Altezza: 81mm  &nbsp;","og_url":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/","og_site_name":"Dentled com","article_modified_time":"2025-03-12T08:36:54+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/","url":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/","name":"PHL14 DUO - Apparecchi a LED per sale di trattamento odontoiatriche","isPartOf":{"@id":"https:\/\/www.dentled.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/#primaryimage"},"image":{"@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg","datePublished":"2022-06-24T13:19:31+00:00","dateModified":"2025-03-12T08:36:54+00:00","breadcrumb":{"@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/#primaryimage","url":"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg","contentUrl":"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg","width":1080,"height":1080,"caption":"save energy, full spectrum daylight, better work, CRI97"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dentled.com\/it\/prodotto\/phl14-duo-apparecchi-a-led-per-sale-di-trattamento-odontoiatriche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dentled.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotto","item":"https:\/\/www.dentled.com\/it\/prodotto\/"},{"@type":"ListItem","position":3,"name":"PHL14 DUO &#8211; Apparecchi a LED per sale di trattamento odontoiatriche"}]},{"@type":"WebSite","@id":"https:\/\/www.dentled.com\/it\/#website","url":"https:\/\/www.dentled.com\/it\/","name":"Dentled com","description":"Lighting for dental care","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dentled.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/product\/2336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/media\/2344"}],"wp:attachment":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/media?parent=2336"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/product_brand?post=2336"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/product_cat?post=2336"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/product_tag?post=2336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}