{"id":2428,"date":"2023-05-10T12:37:44","date_gmt":"2023-05-10T12:37:44","guid":{"rendered":"https:\/\/www.dentled.com\/notizie\/"},"modified":"2025-10-22T05:05:51","modified_gmt":"2025-10-22T05:05:51","slug":"notizie","status":"publish","type":"page","link":"https:\/\/www.dentled.com\/it\/notizie\/","title":{"rendered":"Notizie"},"content":{"rendered":"<h3>Notizie e aggiornamenti su Dentled<\/h3>\n<p>Rimani aggiornato sulle ultime novit\u00e0 e tendenze del tuo settore con le nostre pagine dedicate alle notizie.<\/p>\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1\" >\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/studi-sui-benefici-per-la-salute-dellilluminazione-a-spettro-completo\/\" class=\"plain\" aria-label=\"Studi sui benefici per la salute dell&#8217;illuminazione a spettro completo\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"PHU nello showroom di Arseus\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2024\/05\/PHU-dental-showroom-Arseus.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/studi-sui-benefici-per-la-salute-dellilluminazione-a-spettro-completo\/\" class=\"plain\">Studi sui benefici per la salute dell&#8217;illuminazione a spettro completo<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mag<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/illuminazione-per-cliniche-odontoiatriche-e-divieto-di-vendita-di-illuminazione-fluorescente-rohs-2011-65-ue\/\" class=\"plain\" aria-label=\"Illuminazione per cliniche odontoiatriche e divieto di vendita di illuminazione fluorescente RoHS 2011\/65\/UE\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dentled DL60: illuminazione a LED a spettro completo con luce diurna per ambulatori odontoiatrici\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/03\/Untitled-design-60.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/illuminazione-per-cliniche-odontoiatriche-e-divieto-di-vendita-di-illuminazione-fluorescente-rohs-2011-65-ue\/\" class=\"plain\">Illuminazione per cliniche odontoiatriche e divieto di vendita di illuminazione fluorescente RoHS 2011\/65\/UE<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tRoHS: divieto dell'UE sull'illuminazione fluorescente; Sostituisci le tue luci con luci LED ad alta efficienza [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">28<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Lug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/formazione-sullergonomia-presso-goodguys-dental-con-a-dec\/\" class=\"plain\" aria-label=\"Formazione sull&#8217;ergonomia presso Goodguys Dental con A-dec\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-320x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"PHL22 Luci a LED nere per ambulatorio dentistico\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-320x400.jpg 320w, https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-640x800.jpg 640w, https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-768x960.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-247x309.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting-512x640.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2023\/07\/Training-goodguys-dental-treatmentroom-lighting.jpg 1080w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/formazione-sullergonomia-presso-goodguys-dental-con-a-dec\/\" class=\"plain\">Formazione sull&#8217;ergonomia presso Goodguys Dental con A-dec<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">03<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Lug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/facciamo-luce-sui-vantaggi-dellaggiornamento-allilluminazione-a-led-nella-tua-clinica-odontoiatrica\/\" class=\"plain\" aria-label=\"Facciamo luce sui vantaggi dell&#8217;aggiornamento all&#8217;illuminazione a LED nella tua clinica odontoiatrica\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Illuminazione Dentled per studi dentistici. Luce diurna a spettro completo a risparmio energetico per lavorare meglio\" srcset=\"https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-400x400.jpg 400w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-800x800.jpg 800w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-280x280.jpg 280w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-768x768.jpg 768w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-247x247.jpg 247w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-512x512.jpg 512w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting-100x100.jpg 100w, https:\/\/www.dentled.com\/wp-content\/uploads\/2022\/06\/Dentled-PHL14-Duo-dental-treatment-room-clinic-lighting.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.dentled.com\/it\/facciamo-luce-sui-vantaggi-dellaggiornamento-allilluminazione-a-led-nella-tua-clinica-odontoiatrica\/\" class=\"plain\">Facciamo luce sui vantaggi dell&#8217;aggiornamento all&#8217;illuminazione a LED nella tua clinica odontoiatrica<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tIn qualit\u00e0 di dentista, vuoi fornire la migliore assistenza possibile ai tuoi pazienti. Ma hai [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mag<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Notizie e aggiornamenti su Dentled Rimani aggiornato sulle ultime novit\u00e0 e tendenze del tuo settore con le nostre pagine dedicate alle notizie.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2428","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notizie% at Illuminazione dentale per i professionisti del settore dentale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dentled.com\/it\/notizie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notizie% at Illuminazione dentale per i professionisti del settore dentale\" \/>\n<meta property=\"og:description\" content=\"Notizie e aggiornamenti su Dentled Rimani aggiornato sulle ultime novit\u00e0 e tendenze del tuo settore con le nostre pagine dedicate alle notizie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dentled.com\/it\/notizie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentled com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T05:05:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/notizie\\\/\",\"url\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/notizie\\\/\",\"name\":\"Notizie% at Illuminazione dentale per i professionisti del settore dentale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/#website\"},\"datePublished\":\"2023-05-10T12:37:44+00:00\",\"dateModified\":\"2025-10-22T05:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/notizie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dentled.com\\\/it\\\/notizie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/notizie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/\",\"name\":\"Dentled com\",\"description\":\"Lighting for dental care\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dentled.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notizie% at Illuminazione dentale per i professionisti del settore dentale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dentled.com\/it\/notizie\/","og_locale":"it_IT","og_type":"article","og_title":"Notizie% at Illuminazione dentale per i professionisti del settore dentale","og_description":"Notizie e aggiornamenti su Dentled Rimani aggiornato sulle ultime novit\u00e0 e tendenze del tuo settore con le nostre pagine dedicate alle notizie.","og_url":"https:\/\/www.dentled.com\/it\/notizie\/","og_site_name":"Dentled com","article_modified_time":"2025-10-22T05:05:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dentled.com\/it\/notizie\/","url":"https:\/\/www.dentled.com\/it\/notizie\/","name":"Notizie% at Illuminazione dentale per i professionisti del settore dentale","isPartOf":{"@id":"https:\/\/www.dentled.com\/it\/#website"},"datePublished":"2023-05-10T12:37:44+00:00","dateModified":"2025-10-22T05:05:51+00:00","breadcrumb":{"@id":"https:\/\/www.dentled.com\/it\/notizie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dentled.com\/it\/notizie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dentled.com\/it\/notizie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dentled.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie"}]},{"@type":"WebSite","@id":"https:\/\/www.dentled.com\/it\/#website","url":"https:\/\/www.dentled.com\/it\/","name":"Dentled com","description":"Lighting for dental care","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dentled.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/pages\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/comments?post=2428"}],"version-history":[{"count":0,"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/pages\/2428\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dentled.com\/it\/wp-json\/wp\/v2\/media?parent=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}